{"id":2066,"date":"2018-01-15T18:18:19","date_gmt":"2018-01-15T15:18:19","guid":{"rendered":"http:\/\/pbjss.edu.lv\/?post_type=tribe_events&#038;p=2066"},"modified":"2018-01-15T18:18:19","modified_gmt":"2018-01-15T15:18:19","slug":"jekabpils-46-atkl-cempionats","status":"publish","type":"tribe_events","link":"https:\/\/pbjss.edu.lv\/en\/event\/jekabpils-46-atkl-cempionats\/","title":{"rendered":"J\u0113kabpils 46.atkl.\u010dempion\u0101ts"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[24],"class_list":["post-2066","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-galda-teniss","cat_galda-teniss"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>J\u0113kabpils 46.atkl.\u010dempion\u0101ts - Prei\u013cu novada b\u0113rnu un jaunie\u0161u sporta skola<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"J\u0113kabpils 46.atkl.\u010dempion\u0101ts - Prei\u013cu novada b\u0113rnu un jaunie\u0161u sporta skola\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pbjss.edu.lv\/en\/event\/jekabpils-46-atkl-cempionats\/\" \/>\n<meta property=\"og:site_name\" content=\"Prei\u013cu novada b\u0113rnu un jaunie\u0161u sporta skola\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pbjss\/?eid=ARAe9wQ7MGM0FQFTVX7QEebpfAfe5hv7HvoN-v1Jv13lgtTNi-DDzJx16PrauJn_wRTcN6k13xTyjf4n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pbjss.edu.lv\\\/event\\\/jekabpils-46-atkl-cempionats\\\/\",\"url\":\"https:\\\/\\\/pbjss.edu.lv\\\/event\\\/jekabpils-46-atkl-cempionats\\\/\",\"name\":\"J\u0113kabpils 46.atkl.\u010dempion\u0101ts - Prei\u013cu novada b\u0113rnu un jaunie\u0161u sporta skola\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pbjss.edu.lv\\\/#website\"},\"datePublished\":\"2018-01-15T15:18:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pbjss.edu.lv\\\/event\\\/jekabpils-46-atkl-cempionats\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pbjss.edu.lv\\\/event\\\/jekabpils-46-atkl-cempionats\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pbjss.edu.lv\\\/event\\\/jekabpils-46-atkl-cempionats\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/pbjss.edu.lv\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Notikumi\",\"item\":\"https:\\\/\\\/pbjss.edu.lv\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"J\u0113kabpils 46.atkl.\u010dempion\u0101ts\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pbjss.edu.lv\\\/#website\",\"url\":\"https:\\\/\\\/pbjss.edu.lv\\\/\",\"name\":\"Prei\u013cu novada b\u0113rnu un jaunie\u0161u sporta skola\",\"description\":\"Augst\u0101k, t\u0101l\u0101k, stipr\u0101k!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pbjss.edu.lv\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"J\u0113kabpils 46.atkl.\u010dempion\u0101ts - Prei\u013cu novada b\u0113rnu un jaunie\u0161u sporta skola","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_GB","og_type":"article","og_title":"J\u0113kabpils 46.atkl.\u010dempion\u0101ts - Prei\u013cu novada b\u0113rnu un jaunie\u0161u sporta skola","og_url":"https:\/\/pbjss.edu.lv\/en\/event\/jekabpils-46-atkl-cempionats\/","og_site_name":"Prei\u013cu novada b\u0113rnu un jaunie\u0161u sporta skola","article_publisher":"https:\/\/www.facebook.com\/pbjss\/?eid=ARAe9wQ7MGM0FQFTVX7QEebpfAfe5hv7HvoN-v1Jv13lgtTNi-DDzJx16PrauJn_wRTcN6k13xTyjf4n","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pbjss.edu.lv\/event\/jekabpils-46-atkl-cempionats\/","url":"https:\/\/pbjss.edu.lv\/event\/jekabpils-46-atkl-cempionats\/","name":"J\u0113kabpils 46.atkl.\u010dempion\u0101ts - Prei\u013cu novada b\u0113rnu un jaunie\u0161u sporta skola","isPartOf":{"@id":"https:\/\/pbjss.edu.lv\/#website"},"datePublished":"2018-01-15T15:18:19+00:00","breadcrumb":{"@id":"https:\/\/pbjss.edu.lv\/event\/jekabpils-46-atkl-cempionats\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pbjss.edu.lv\/event\/jekabpils-46-atkl-cempionats\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/pbjss.edu.lv\/event\/jekabpils-46-atkl-cempionats\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pbjss.edu.lv\/"},{"@type":"ListItem","position":2,"name":"Notikumi","item":"https:\/\/pbjss.edu.lv\/events\/"},{"@type":"ListItem","position":3,"name":"J\u0113kabpils 46.atkl.\u010dempion\u0101ts"}]},{"@type":"WebSite","@id":"https:\/\/pbjss.edu.lv\/#website","url":"https:\/\/pbjss.edu.lv\/","name":"Prei\u013cu novada b\u0113rnu un jaunie\u0161u sporta skola","description":"Augst\u0101k, t\u0101l\u0101k, stipr\u0101k!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pbjss.edu.lv\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/pbjss.edu.lv\/en\/wp-json\/wp\/v2\/tribe_events\/2066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pbjss.edu.lv\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/pbjss.edu.lv\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/pbjss.edu.lv\/en\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":0,"href":"https:\/\/pbjss.edu.lv\/en\/wp-json\/wp\/v2\/tribe_events\/2066\/revisions"}],"wp:attachment":[{"href":"https:\/\/pbjss.edu.lv\/en\/wp-json\/wp\/v2\/media?parent=2066"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pbjss.edu.lv\/en\/wp-json\/wp\/v2\/tags?post=2066"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/pbjss.edu.lv\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=2066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}